{"id":939,"date":"2022-10-05T14:18:43","date_gmt":"2022-10-05T12:18:43","guid":{"rendered":"https:\/\/tsvmusberg.de\/turnen\/events\/eltern-kind-turnen\/"},"modified":"2025-03-13T14:50:19","modified_gmt":"2025-03-13T13:50:19","slug":"eltern-kind-turnen","status":"publish","type":"mec-events","link":"https:\/\/tsvmusberg.de\/turnen\/events\/eltern-kind-turnen\/","title":{"rendered":"Eltern-Kind-Turnen (bei Laura)"},"content":{"rendered":"<h5>Kinder im Alter von 1,5-3,5 Jahren<\/h5>\n<p>Im Eltern-Kind-Turnen lernen Kinder zusammen mit ihren Eltern die Vielfalt des Kinderturnens kennen. Hierbei steht das Sammeln vielseitiger Bewegungserfahrungen, mit und ohne Materialien\/Ger\u00e4ten im Vordergrund (Quelle: <a title=\"http:\/\/www.dtb.de\/\" href=\"http:\/\/www.dtb.de\">www.dtb.de<\/a> ).<\/p>\n<p>Inhalte: Bewegungslieder, Kleinger\u00e4te, Ger\u00e4telandschaften<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kinder im Alter von 1,5-3,5 Jahren Im Eltern-Kind-Turnen lernen Kinder zusammen mit ihren Eltern die Vielfalt des Kinderturnens kennen. Hierbei steht das Sammeln vielseitiger Bewegungserfahrungen, mit und ohne Materialien\/Ger\u00e4ten im&#8230;<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","tags":[],"mec_category":[16],"class_list":["post-939","mec-events","type-mec-events","status-publish","mec_category-sportprogramm"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Eltern-Kind-Turnen (bei Laura) | Turnen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tsvmusberg.de\/turnen\/events\/eltern-kind-turnen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eltern-Kind-Turnen (bei Laura) | Turnen\" \/>\n<meta property=\"og:description\" content=\"Kinder im Alter von 1,5-3,5 Jahren Im Eltern-Kind-Turnen lernen Kinder zusammen mit ihren Eltern die Vielfalt des Kinderturnens kennen. Hierbei steht das Sammeln vielseitiger Bewegungserfahrungen, mit und ohne Materialien\/Ger\u00e4ten im...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tsvmusberg.de\/turnen\/events\/eltern-kind-turnen\/\" \/>\n<meta property=\"og:site_name\" content=\"Turnen\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-13T13:50:19+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/events\\\/eltern-kind-turnen\\\/\",\"url\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/events\\\/eltern-kind-turnen\\\/\",\"name\":\"Eltern-Kind-Turnen (bei Laura) | Turnen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/#website\"},\"datePublished\":\"2022-10-05T12:18:43+00:00\",\"dateModified\":\"2025-03-13T13:50:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/events\\\/eltern-kind-turnen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/events\\\/eltern-kind-turnen\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/events\\\/eltern-kind-turnen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Eltern-Kind-Turnen (bei Laura)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/#website\",\"url\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/\",\"name\":\"Turnen\",\"description\":\"Turn- und Sportvereinigung in Leinfelden-Echterdingen\",\"publisher\":{\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/#organization\",\"name\":\"TSV Musberg e.V.\",\"url\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/tsv-musberg-logo.svg\",\"contentUrl\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/wp-content\\\/uploads\\\/sites\\\/21\\\/tsv-musberg-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"TSV Musberg e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/turnen\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Eltern-Kind-Turnen (bei Laura) | Turnen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tsvmusberg.de\/turnen\/events\/eltern-kind-turnen\/","og_locale":"de_DE","og_type":"article","og_title":"Eltern-Kind-Turnen (bei Laura) | Turnen","og_description":"Kinder im Alter von 1,5-3,5 Jahren Im Eltern-Kind-Turnen lernen Kinder zusammen mit ihren Eltern die Vielfalt des Kinderturnens kennen. Hierbei steht das Sammeln vielseitiger Bewegungserfahrungen, mit und ohne Materialien\/Ger\u00e4ten im...","og_url":"https:\/\/tsvmusberg.de\/turnen\/events\/eltern-kind-turnen\/","og_site_name":"Turnen","article_modified_time":"2025-03-13T13:50:19+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tsvmusberg.de\/turnen\/events\/eltern-kind-turnen\/","url":"https:\/\/tsvmusberg.de\/turnen\/events\/eltern-kind-turnen\/","name":"Eltern-Kind-Turnen (bei Laura) | Turnen","isPartOf":{"@id":"https:\/\/tsvmusberg.de\/turnen\/#website"},"datePublished":"2022-10-05T12:18:43+00:00","dateModified":"2025-03-13T13:50:19+00:00","breadcrumb":{"@id":"https:\/\/tsvmusberg.de\/turnen\/events\/eltern-kind-turnen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tsvmusberg.de\/turnen\/events\/eltern-kind-turnen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tsvmusberg.de\/turnen\/events\/eltern-kind-turnen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/tsvmusberg.de\/turnen\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/tsvmusberg.de\/turnen\/events\/"},{"@type":"ListItem","position":3,"name":"Eltern-Kind-Turnen (bei Laura)"}]},{"@type":"WebSite","@id":"https:\/\/tsvmusberg.de\/turnen\/#website","url":"https:\/\/tsvmusberg.de\/turnen\/","name":"Turnen","description":"Turn- und Sportvereinigung in Leinfelden-Echterdingen","publisher":{"@id":"https:\/\/tsvmusberg.de\/turnen\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tsvmusberg.de\/turnen\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/tsvmusberg.de\/turnen\/#organization","name":"TSV Musberg e.V.","url":"https:\/\/tsvmusberg.de\/turnen\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tsvmusberg.de\/turnen\/#\/schema\/logo\/image\/","url":"https:\/\/tsvmusberg.de\/turnen\/wp-content\/uploads\/sites\/21\/tsv-musberg-logo.svg","contentUrl":"https:\/\/tsvmusberg.de\/turnen\/wp-content\/uploads\/sites\/21\/tsv-musberg-logo.svg","width":1,"height":1,"caption":"TSV Musberg e.V."},"image":{"@id":"https:\/\/tsvmusberg.de\/turnen\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/tsvmusberg.de\/turnen\/wp-json\/wp\/v2\/mec-events\/939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tsvmusberg.de\/turnen\/wp-json\/wp\/v2\/mec-events"}],"about":[{"href":"https:\/\/tsvmusberg.de\/turnen\/wp-json\/wp\/v2\/types\/mec-events"}],"author":[{"embeddable":true,"href":"https:\/\/tsvmusberg.de\/turnen\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/tsvmusberg.de\/turnen\/wp-json\/wp\/v2\/comments?post=939"}],"wp:attachment":[{"href":"https:\/\/tsvmusberg.de\/turnen\/wp-json\/wp\/v2\/media?parent=939"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tsvmusberg.de\/turnen\/wp-json\/wp\/v2\/tags?post=939"},{"taxonomy":"mec_category","embeddable":true,"href":"https:\/\/tsvmusberg.de\/turnen\/wp-json\/wp\/v2\/mec_category?post=939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}