{"id":1808,"date":"2023-06-30T18:47:28","date_gmt":"2023-06-30T16:47:28","guid":{"rendered":"https:\/\/tsvmusberg.de\/fussball\/?p=1808"},"modified":"2023-07-05T16:44:44","modified_gmt":"2023-07-05T14:44:44","slug":"bezirkspokalfinale-stuttgart-2023","status":"publish","type":"post","link":"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/","title":{"rendered":"Bezirkspokalfinale Stuttgart 2023 &#8211; R\u00fcckblick"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Spannung, Stimmung und hochklassiger Sport beim Bezirkspokalfinaltag&#8221;][\/split_line_heading][divider line_type=&#8221;No Line&#8221;][vc_column_text]<span data-contrast=\"auto\">Am Donnerstag, den 18. Mai fand in Musberg das mit Spannung erwartete Bezirkspokalfinale des W\u00fcrttembergischen Fu\u00dfballverbandes Bezirk Stuttgart statt. Es war ein Tag voller unvergesslicher Momente und einer unbeschreiblichen Atmosph\u00e4re, welchen wir als TSV Musberg f\u00fcr immer in unserem Herzen tragen werden.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Auch wenn man das \u201eFinale Dahoim\u201c gerne mit einem Sieg gekr\u00f6nt h\u00e4tte, war es dennoch eine tolle Veranstaltung, die ohne die vielen helfenden H\u00e4nde nicht m\u00f6glich gewesen w\u00e4re. Ein besonderer Dank gilt daher den \u00fcber 160 Helferinnen und Helfern aus allen Abteilungen des TSV Musberg. Nach \u00fcber vier Jahren ohne Veranstaltung haben sie Unglaubliches geleistet und ein solches Event auf die Beine gestellt. Wir k\u00f6nnten nicht stolzer sein!<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Impressionen vom Bezirkspokalfinale&#8221;][\/split_line_heading][divider line_type=&#8221;No Line&#8221;][vc_gallery type=&#8221;flickity_style&#8221; images=&#8221;1814,1813,1811,1810,1815,1816,1818,1820,1809&#8243; flickity_spacing=&#8221;default&#8221; flickity_controls=&#8221;pagination&#8221; flickity_overflow=&#8221;visible&#8221; flickity_wrap_around=&#8221;no-wrap&#8221; flickity_desktop_columns=&#8221;3&#8243; flickity_small_desktop_columns=&#8221;3&#8243; flickity_tablet_columns=&#8221;2&#8243; flickity_phone_columns=&#8221;1&#8243; flickity_box_shadow=&#8221;medium_depth&#8221; image_loading=&#8221;default&#8221; onclick=&#8221;link_image&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;100px&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][divider line_type=&#8221;No Line&#8221;][vc_column_text]<span data-contrast=\"auto\">Der Pokalfinaltag begann mit dem Eintreffen der C-Jugend des MTV Stuttgart und der Sportvg. Feuerbach, die sich bereits um 09.30 Uhr im Finale gegen\u00fcberstanden. In einem hochklassigen Spiel konnte sich schlie\u00dflich die C-Jugend des MTV Stuttgart II mit einem klaren 5:0 Sieg den Titel sichern. Der Jubel kannte keine Grenzen und der Pokalsieg wurde auf dem Balkon geb\u00fchrend gefeiert.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Anschlie\u00dfend ging es nahtlos weiter mit hochklassigem Jugendfu\u00dfball. Die B-Junioren der SG Weilimdorf und des SV Sillenbuch boten den Zuschauern ein spannendes Spiel, das die SG Weilimdorf knapp mit 2:1 f\u00fcr sich entscheiden konnte. Jubel und strahlende Gesichter waren das Ergebnis dieser spannenden Begegnung.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Im letzten Jugendfinale standen sich die A-Jugend der Sportvg. Feuerbach und der SG Weilimdorf gegen\u00fcber. Es sah nach einer Verl\u00e4ngerung aus, doch in der 6. Minute der Nachspielzeit erzielte Feuerbach den entscheidenden Siegtreffer. Ein Herzschlagfinale, das Freude und Entt\u00e4uschung gleicherma\u00dfen mit sich brachte.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span>[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1817&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;100px&#8221; equal_height=&#8221;yes&#8221; content_placement=&#8221;middle&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][image_with_animation image_url=&#8221;1821&#8243; image_size=&#8221;full&#8221; animation_type=&#8221;entrance&#8221; animation=&#8221;Fade In&#8221; animation_easing=&#8221;default&#8221; animation_movement_type=&#8221;transform_y&#8221; hover_animation=&#8221;none&#8221; alignment=&#8221;center&#8221; img_link_large=&#8221;yes&#8221; border_radius=&#8221;none&#8221; box_shadow=&#8221;none&#8221; image_loading=&#8221;default&#8221; max_width=&#8221;100%&#8221; max_width_mobile=&#8221;default&#8221;][\/vc_column][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<span data-contrast=\"auto\">Am Nachmittag standen sich die Frauenmannschaften der SGM TSV Heumaden\/SV Sillenbuch und der Serienpokalsieger Sportvg. Feuerbach gegen\u00fcber. Feuerbach wurde seiner klaren Favoritenrolle gerecht und siegte am Ende deutlich mit 5:0 und holte sich verdient den Pokal.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Um 18.30 Uhr war alles bereit f\u00fcr den H\u00f6hepunkt des Tages. Die Zuschauer str\u00f6mten in Scharen in das Musberger Sportzentrum, um sich das tolle Erlebnis eines Pokalfinales vor heimischem Publikum in Musberg nicht entgehen zu lassen. Die Vorfreude und positive Energie war f\u00f6rmlich zu sp\u00fcren. Trainer Valentin Haug gab im Interview mit Robert Raff die klare Marschrichtung vor. Die Mannschaft habe hart gearbeitet und sich diesen Moment redlich verdient. Mit einer kompakten Mannschaftsleistung wollte man dem starken Gegner aus Stammheim keinen Raum zur Entfaltung lassen, um den Traum vom Pokalsieg wahr werden zu lassen. Wie wir jetzt wissen, hat es leider nicht ganz gereicht &#8211; dennoch hat die Mannschaft alles auf den Platz geworfen. Am Ende waren es Kleinigkeiten, die den Ausschlag gaben und so musste man sich mit 1:0 geschlagen geben, wobei der fr\u00fche F\u00fchrungstreffer den Unterschied ausmachte und die Musberger ihre 45-min\u00fctige \u00dcberzahl nicht nutzen konnten.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Auch wenn es diesmal nicht geklappt hat, werden wir im n\u00e4chsten Jahr wieder angreifen und den Pokal holen, denn wie hei\u00dft es so sch\u00f6n? Aller guten Dinge sind drei! Mit der sensationellen Unterst\u00fctzung unserer Fans wird uns das sicher gelingen.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;100&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; advanced_gradient_angle=&#8221;0&#8243; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; gradient_type=&#8221;default&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; column_position=&#8221;default&#8221; advanced_gradient_angle=&#8221;0&#8243; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; animation_type=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; gradient_type=&#8221;default&#8221;][split_line_heading animation_type=&#8221;line-reveal-by-space&#8221; font_style=&#8221;h5&#8243; line_reveal_by_space_text_effect=&#8221;default&#8221; content_alignment=&#8221;default&#8221; mobile_content_alignment=&#8221;inherit&#8221; link_target=&#8221;_self&#8221; text_content=&#8221;Vielen Dank f\u00fcr Euren Einsatz&#8221;][\/split_line_heading][divider line_type=&#8221;No Line&#8221;][vc_column_text]<span data-contrast=\"auto\">An dieser Stelle m\u00f6chten wir uns noch einmal bei allen Beteiligten, den Spielern, Trainern, Organisatoren, Helfern und nat\u00fcrlich den Fans bedanken. Ihr alle habt diesen Tag zu etwas Besonderem gemacht. Eure Leidenschaft und euer Einsatz haben das Bezirkspokalfinale zu einem echten Highlight werden lassen. Neben den spannenden Spielen war es die perfekte Mischung aus Unterhaltung, Verpflegung und Tanz, die diesen Tag zu einem wahren Fu\u00dfballfest machte. Die Stimmung war elektrisierend, die Gesichter strahlten vor Freude und Begeisterung. Auch das Wetter spielte mit und setzte dem Tag die Krone auf. Strahlender Sonnenschein begleitete uns von Anfang bis Ende und sorgte f\u00fcr beste Bedingungen auf und neben dem Platz. Musberg hat gezeigt, dass hier Sport und Ehrenamt gelebt werden.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-ccp-props=\"{}\">\u00a0<\/span><span data-contrast=\"auto\">Bewahren wir diese sch\u00f6nen Erinnerungen in unseren Herzen und freuen wir uns auf die kommenden Veranstaltungen. Der TSV Musberg ist bereit f\u00fcr weitere spektakul\u00e4re Veranstaltungen und wir wissen, dass wir auf die Unterst\u00fctzung unserer gro\u00dfartigen Musberger Gemeinschaft z\u00e4hlen k\u00f6nnen.<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Bis n\u00e4chstes Jahr, wenn wir wieder gemeinsam feiern und den Sieg nach Musberg holen. Wir sind bereit!<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Mit sportlichen Gr\u00fc\u00dfen,<\/span><span data-ccp-props=\"{}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Lucas Schlegel<\/span><span data-ccp-props=\"{}\">\u00a0<\/span>[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overflow=&#8221;visible&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_direction_desktop=&#8221;default&#8221; column_element_spacing=&#8221;default&#8221; desktop_text_alignment=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_backdrop_filter=&#8221;none&#8221; column_shadow=&#8221;none&#8221;&#8230;<\/p>\n","protected":false},"author":3,"featured_media":1819,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,56],"tags":[],"class_list":{"0":"post-1808","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-news","8":"category-top-news"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bezirkspokalfinale Stuttgart 2023 - R\u00fcckblick | Fu\u00dfball<\/title>\n<meta name=\"description\" content=\"Am Donnerstag, den 18. Mai fand in Musberg das mit Spannung erwartete Bezirkspokalfinale des W\u00fcrttembergischen Fu\u00dfballverbandes Bezirk Stuttgart statt. Es war ein Tag voller unvergesslicher Momente und einer unbeschreiblichen Atmosph\u00e4re f\u00fcr den TSV Musberg.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bezirkspokalfinale Stuttgart 2023 - R\u00fcckblick | Fu\u00dfball\" \/>\n<meta property=\"og:description\" content=\"Am Donnerstag, den 18. Mai fand in Musberg das mit Spannung erwartete Bezirkspokalfinale des W\u00fcrttembergischen Fu\u00dfballverbandes Bezirk Stuttgart statt. Es war ein Tag voller unvergesslicher Momente und einer unbeschreiblichen Atmosph\u00e4re f\u00fcr den TSV Musberg.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Fu\u00dfball\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-30T16:47:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-05T14:44:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tsvmusberg.de\/fussball\/wp-content\/uploads\/sites\/14\/Stimmung-beim-TSV-Musberg-scaled.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"lrs\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"lrs\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/news\\\/bezirkspokalfinale-stuttgart-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/news\\\/bezirkspokalfinale-stuttgart-2023\\\/\"},\"author\":{\"name\":\"lrs\",\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/#\\\/schema\\\/person\\\/9f4653fb697695d35cc5b50a6d82c6eb\"},\"headline\":\"Bezirkspokalfinale Stuttgart 2023 &#8211; R\u00fcckblick\",\"datePublished\":\"2023-06-30T16:47:28+00:00\",\"dateModified\":\"2023-07-05T14:44:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/news\\\/bezirkspokalfinale-stuttgart-2023\\\/\"},\"wordCount\":2023,\"publisher\":{\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/news\\\/bezirkspokalfinale-stuttgart-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/Stimmung-beim-TSV-Musberg-scaled.jpeg\",\"articleSection\":[\"News\",\"Top News\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/news\\\/bezirkspokalfinale-stuttgart-2023\\\/\",\"url\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/news\\\/bezirkspokalfinale-stuttgart-2023\\\/\",\"name\":\"Bezirkspokalfinale Stuttgart 2023 - R\u00fcckblick | Fu\u00dfball\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/news\\\/bezirkspokalfinale-stuttgart-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/news\\\/bezirkspokalfinale-stuttgart-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/Stimmung-beim-TSV-Musberg-scaled.jpeg\",\"datePublished\":\"2023-06-30T16:47:28+00:00\",\"dateModified\":\"2023-07-05T14:44:44+00:00\",\"description\":\"Am Donnerstag, den 18. Mai fand in Musberg das mit Spannung erwartete Bezirkspokalfinale des W\u00fcrttembergischen Fu\u00dfballverbandes Bezirk Stuttgart statt. Es war ein Tag voller unvergesslicher Momente und einer unbeschreiblichen Atmosph\u00e4re f\u00fcr den TSV Musberg.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/news\\\/bezirkspokalfinale-stuttgart-2023\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/news\\\/bezirkspokalfinale-stuttgart-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/news\\\/bezirkspokalfinale-stuttgart-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/Stimmung-beim-TSV-Musberg-scaled.jpeg\",\"contentUrl\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/Stimmung-beim-TSV-Musberg-scaled.jpeg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/news\\\/bezirkspokalfinale-stuttgart-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bezirkspokalfinale Stuttgart 2023 &#8211; R\u00fcckblick\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/#website\",\"url\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/\",\"name\":\"Fu\u00dfball\",\"description\":\"Turn- und Sportvereinigung in Leinfelden-Echterdingen\",\"publisher\":{\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/#organization\",\"name\":\"TSV Musberg e.V.\",\"url\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/tsv-musberg-logo.svg\",\"contentUrl\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/tsv-musberg-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"TSV Musberg e.V.\"},\"image\":{\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/#\\\/schema\\\/person\\\/9f4653fb697695d35cc5b50a6d82c6eb\",\"name\":\"lrs\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db6b62597ae923d7c927cd344e0e5f3baf4a443e76609c94be578e3b87869846?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db6b62597ae923d7c927cd344e0e5f3baf4a443e76609c94be578e3b87869846?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/db6b62597ae923d7c927cd344e0e5f3baf4a443e76609c94be578e3b87869846?s=96&d=mm&r=g\",\"caption\":\"lrs\"},\"url\":\"https:\\\/\\\/tsvmusberg.de\\\/fussball\\\/author\\\/test\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bezirkspokalfinale Stuttgart 2023 - R\u00fcckblick | Fu\u00dfball","description":"Am Donnerstag, den 18. Mai fand in Musberg das mit Spannung erwartete Bezirkspokalfinale des W\u00fcrttembergischen Fu\u00dfballverbandes Bezirk Stuttgart statt. Es war ein Tag voller unvergesslicher Momente und einer unbeschreiblichen Atmosph\u00e4re f\u00fcr den TSV Musberg.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/","og_locale":"de_DE","og_type":"article","og_title":"Bezirkspokalfinale Stuttgart 2023 - R\u00fcckblick | Fu\u00dfball","og_description":"Am Donnerstag, den 18. Mai fand in Musberg das mit Spannung erwartete Bezirkspokalfinale des W\u00fcrttembergischen Fu\u00dfballverbandes Bezirk Stuttgart statt. Es war ein Tag voller unvergesslicher Momente und einer unbeschreiblichen Atmosph\u00e4re f\u00fcr den TSV Musberg.","og_url":"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/","og_site_name":"Fu\u00dfball","article_published_time":"2023-06-30T16:47:28+00:00","article_modified_time":"2023-07-05T14:44:44+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/tsvmusberg.de\/fussball\/wp-content\/uploads\/sites\/14\/Stimmung-beim-TSV-Musberg-scaled.jpeg","type":"image\/jpeg"}],"author":"lrs","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"lrs","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/#article","isPartOf":{"@id":"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/"},"author":{"name":"lrs","@id":"https:\/\/tsvmusberg.de\/fussball\/#\/schema\/person\/9f4653fb697695d35cc5b50a6d82c6eb"},"headline":"Bezirkspokalfinale Stuttgart 2023 &#8211; R\u00fcckblick","datePublished":"2023-06-30T16:47:28+00:00","dateModified":"2023-07-05T14:44:44+00:00","mainEntityOfPage":{"@id":"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/"},"wordCount":2023,"publisher":{"@id":"https:\/\/tsvmusberg.de\/fussball\/#organization"},"image":{"@id":"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/tsvmusberg.de\/fussball\/wp-content\/uploads\/sites\/14\/Stimmung-beim-TSV-Musberg-scaled.jpeg","articleSection":["News","Top News"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/","url":"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/","name":"Bezirkspokalfinale Stuttgart 2023 - R\u00fcckblick | Fu\u00dfball","isPartOf":{"@id":"https:\/\/tsvmusberg.de\/fussball\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/#primaryimage"},"image":{"@id":"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/tsvmusberg.de\/fussball\/wp-content\/uploads\/sites\/14\/Stimmung-beim-TSV-Musberg-scaled.jpeg","datePublished":"2023-06-30T16:47:28+00:00","dateModified":"2023-07-05T14:44:44+00:00","description":"Am Donnerstag, den 18. Mai fand in Musberg das mit Spannung erwartete Bezirkspokalfinale des W\u00fcrttembergischen Fu\u00dfballverbandes Bezirk Stuttgart statt. Es war ein Tag voller unvergesslicher Momente und einer unbeschreiblichen Atmosph\u00e4re f\u00fcr den TSV Musberg.","breadcrumb":{"@id":"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/#primaryimage","url":"https:\/\/tsvmusberg.de\/fussball\/wp-content\/uploads\/sites\/14\/Stimmung-beim-TSV-Musberg-scaled.jpeg","contentUrl":"https:\/\/tsvmusberg.de\/fussball\/wp-content\/uploads\/sites\/14\/Stimmung-beim-TSV-Musberg-scaled.jpeg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/tsvmusberg.de\/fussball\/news\/bezirkspokalfinale-stuttgart-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/tsvmusberg.de\/fussball\/"},{"@type":"ListItem","position":2,"name":"Bezirkspokalfinale Stuttgart 2023 &#8211; R\u00fcckblick"}]},{"@type":"WebSite","@id":"https:\/\/tsvmusberg.de\/fussball\/#website","url":"https:\/\/tsvmusberg.de\/fussball\/","name":"Fu\u00dfball","description":"Turn- und Sportvereinigung in Leinfelden-Echterdingen","publisher":{"@id":"https:\/\/tsvmusberg.de\/fussball\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tsvmusberg.de\/fussball\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/tsvmusberg.de\/fussball\/#organization","name":"TSV Musberg e.V.","url":"https:\/\/tsvmusberg.de\/fussball\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/tsvmusberg.de\/fussball\/#\/schema\/logo\/image\/","url":"https:\/\/tsvmusberg.de\/fussball\/wp-content\/uploads\/sites\/14\/tsv-musberg-logo.svg","contentUrl":"https:\/\/tsvmusberg.de\/fussball\/wp-content\/uploads\/sites\/14\/tsv-musberg-logo.svg","width":1,"height":1,"caption":"TSV Musberg e.V."},"image":{"@id":"https:\/\/tsvmusberg.de\/fussball\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/tsvmusberg.de\/fussball\/#\/schema\/person\/9f4653fb697695d35cc5b50a6d82c6eb","name":"lrs","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/db6b62597ae923d7c927cd344e0e5f3baf4a443e76609c94be578e3b87869846?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/db6b62597ae923d7c927cd344e0e5f3baf4a443e76609c94be578e3b87869846?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/db6b62597ae923d7c927cd344e0e5f3baf4a443e76609c94be578e3b87869846?s=96&d=mm&r=g","caption":"lrs"},"url":"https:\/\/tsvmusberg.de\/fussball\/author\/test\/"}]}},"_links":{"self":[{"href":"https:\/\/tsvmusberg.de\/fussball\/wp-json\/wp\/v2\/posts\/1808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tsvmusberg.de\/fussball\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tsvmusberg.de\/fussball\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tsvmusberg.de\/fussball\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/tsvmusberg.de\/fussball\/wp-json\/wp\/v2\/comments?post=1808"}],"version-history":[{"count":5,"href":"https:\/\/tsvmusberg.de\/fussball\/wp-json\/wp\/v2\/posts\/1808\/revisions"}],"predecessor-version":[{"id":1826,"href":"https:\/\/tsvmusberg.de\/fussball\/wp-json\/wp\/v2\/posts\/1808\/revisions\/1826"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tsvmusberg.de\/fussball\/wp-json\/wp\/v2\/media\/1819"}],"wp:attachment":[{"href":"https:\/\/tsvmusberg.de\/fussball\/wp-json\/wp\/v2\/media?parent=1808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tsvmusberg.de\/fussball\/wp-json\/wp\/v2\/categories?post=1808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tsvmusberg.de\/fussball\/wp-json\/wp\/v2\/tags?post=1808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}